                        {"id":38942,"date":"2018-02-06T11:30:24","date_gmt":"2018-02-06T09:30:24","guid":{"rendered":"https:\/\/pevgrow.com\/blog\/infusion-de-marihuana\/"},"modified":"2023-12-27T15:14:09","modified_gmt":"2023-12-27T14:14:09","slug":"come-preparare-un-infuso-di-marijuana","status":"publish","type":"post","link":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/","title":{"rendered":"Come preparare un infuso di marijuana"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_22960\" aria-describedby=\"caption-attachment-22960\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22960 size-full\" title=\"Preparare un infuso di marijuana\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg\" alt=\"Preparare un infuso di marijuana\" width=\"575\" height=\"400\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada-300x209.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22960\" class=\"wp-caption-text\">Preparare un infuso di marijuana<\/figcaption><\/figure>\n        <div class=\"hero-unit-pev\">\n            <div class=\"row-fluid\">\n            <div class=\"span2 text-center\">  \n                <picture>\n                    <source media=\"(max-width: 550px)\" srcset=\"\/blog\/wp-content\/uploads\/2019\/08\/noelia.png\">\n                    <source media=\"(min-width: 770px)\" srcset=\"\/blog\/wp-content\/uploads\/2019\/08\/noelia.png\">\n                    <img decoding=\"async\" loading=\"lazy\" src=\"\/blog\/wp-content\/uploads\/2019\/08\/noelia.png\" width=\"100\" height=\"100\" alt=\"Noelia Jim\u00e9nez\" title=\"Noelia Jim\u00e9nez\" class=\"firround\">\n                <\/picture>\n            <\/div>\n            <div class=\"span10 firtexto\">\n                <div class=\"firtit\"><a href=\"\/blog\/it\/author\/noelia-jimenez\/\">Noelia Jim\u00e9nez<\/a><\/div>\n                Adoro cucinare e scrivere di marijuana. Un giorno ho iniziato a fare il burro di marijuana e da allora non ho pi\u00f9 smesso di creare le ricette pi\u00f9 svariate che si possano immaginare.<br>\n                06-02-2018 11:30:24 - Aggiornato: 6 February, 2018\n            <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"pev-redes\">\n            <div class=\"pev-rss-top text-center\">\n                <a class=\"pev-wapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942\" target=\"_blank\" rel=\"nofollow\" alt=\"Whatsapp\" title=\"Whatsapp\"><\/a>\n                <a class=\"pev-telegram\" href=\"https:\/\/t.me\/share\/url?url=https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942&text=Guarda%20questa%20notizia\" target=\"_blank\" rel=\"nofollow\" alt=\"Telegram\" title=\"Telegram\"><\/a>\n                <a class=\"pev-fb\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942\" target=\"_blank\" rel=\"nofollow\" alt=\"Facebook\" title=\"Facebook\"><\/a>\n                <a class=\"pev-tw\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Guarda%20questa%20notizia - https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942\" target=\"_blank\" rel=\"nofollow\" alt=\"Twitter\" title=\"Twitter\"><\/a>\n                <a class=\"pev-mail\" href=\"mailto:?subject=Vedere%20cosa%20ho%20trovato%20in&amp;body=Guarda%20questa%20notizia%20https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942.\" target=\"_blank\" rel=\"nofollow\" alt=\"E-mail\" title=\"E-mail\"><\/a>\n            <\/div>\n        <\/div>\n        \n<p>&nbsp;<\/p>\n<p>Veramente semplici da preparare, gli <a href=\"https:\/\/pevgrow.com\/it\/4956-te-di-marijuana\">t\u00e8 di marijuana<\/a> hanno il vantaggio che gli effetti sono molto pi\u00f9 miti e che impiegano <b>dai 30 ai 90 minuti<\/b> per manifestarsi. Oggi vi diciamo come prepararlo, quali sono le sue propriet\u00e0 e quali effetti produce.<\/p>\n<p>Se ti parlano di infusi, <i>qual \u00e8 la prima cosa che ti viene in mente?<\/i> Probabilmente <b>relax, benessere e salute.<\/b> Tutti questi aspetti che troverai anche in un infuso di marijuana, con la differenza che ha gli effetti che altri infusi di piante officinali, frutti o spezie non hanno.<\/p>\n<p>Ha per\u00f2 in comune il fatto che sia una <b>bevanda sana, facile da preparare<\/b> che, ogni giorno di pi\u00f9, conquista nuovi seguaci e, come tale, presenta anche pi\u00f9 varianti e formati, come vi mostreremo pi\u00f9 avanti.<\/p>\n<p>Di questo, ma soprattutto di <b>come preparare un infuso di marijuana<\/b> da zero,<b> rapidamente e facilmente<\/b>, nonch\u00e9 delle sue propriet\u00e0 o effetti, vogliamo parlarvi oggi in questo post. Allora vieni con noi!<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#%E2%AD%90_Ingredienti\" >\u2b50 Ingredienti<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#%E2%98%95_Come_fare_linfuso_di_marijuana\" >\u2615 Come fare l\u2019infuso di marijuana?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#%F0%9F%9A%80_Proprieta_della_marijuana_in_infusione\" >\ud83d\ude80 Propriet\u00e0 della marijuana in infusione<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#%E2%9C%85_Quali_effetti_produce\" >\u2705 Quali effetti produce?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#%F0%9F%8E%AF_Conclusioni\" >\ud83c\udfaf Conclusioni<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%E2%AD%90_Ingredienti\"><\/span>\u2b50 Ingredienti<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Per preparare un infuso di marijuana avrete bisogno di:<\/p>\n<div class=\"pfbrown\">\n<ul>\n<li><b>Marijuana<\/b>: circa 0,2 grammi (ma \u00e8 molto relativo, perch\u00e9 dipende dalla tolleranza di chi la consuma e anche dalla qualit\u00e0 della marijuana: maggiore \u00e8 la qualit\u00e0, minore sar\u00e0 la quantit\u00e0)<\/li>\n<li>10 grammi di burro non salato.<\/li>\n<li>400 ml di <b>acqua o latte<\/b> (ma che sia intero e di mucca, in modo che contenga del\u00a0 grasso). Se scegli il latte, non \u00e8 necessario utilizzare il burro.<\/li>\n<li>Opzionalmente, puoi combinare questo infuso con altri pi\u00f9 comuni, come <b>camomilla, anice o liquirizia,<\/b> che sono ottimi. E se hai bisogno di addolcirlo, fallo con ingredienti naturali, quali miele o sciroppo d&#8217;agave.<\/li>\n<\/ul>\n<\/div>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22965\" aria-describedby=\"caption-attachment-22965\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22965 size-full\" title=\"Ingredienti necessari per l'infuso di marijuana\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-ingredientes-agua.jpg\" alt=\"Ingredienti necessari per l'infuso di marijuana\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-ingredientes-agua.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-ingredientes-agua-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22965\" class=\"wp-caption-text\">Ingredienti necessari per l&#8217;infuso di marijuana<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<div class=\"pbredd\">Consigliamo di <b>decarbossilare la cannabis prima della cottura,<\/b> poich\u00e9 sebbene durante il processo di preparazione della ricetta la marijuana possa decarbossilarsi, se lo facciamo prima ci assicuriamo che la decarbossilazione sia eseguita correttamente. Se vuoi sapere come si fa, clicca su questo link <a href=\"https:\/\/pevgrow.com\/blog\/it\/decarbossilazione-dellerba-tutto-cio-che-devi-sapere\/\"><b><i>Come decarbossilare la marijuana<\/i><\/b><\/a><b><i>?<\/i><\/b><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E2%98%95_Come_fare_linfuso_di_marijuana\"><\/span>\u2615 <b>Come fare l\u2019infuso di marijuana<\/b>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Ora che hai tutto a portata di mano, vediamo un paio di versioni della preparazione di un infuso di marijuana.<\/p>\n<p>Nel primo caso, faremo un<b> infuso di marijuana con acqua<\/b>. Per far ci\u00f2, i passaggi da seguire sono:<\/p>\n<p>&#8211; Primo, <b>tritare la marijuana nel modo pi\u00f9 fine possibile<\/b>. Puoi farlo manualmente o puoi <b>usare un grinder<\/b>. Quindi mettere a scaldare l&#8217;acqua a fuoco basso e il burro. Quando inizia a bollire, spegni il fuoco.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22968\" aria-describedby=\"caption-attachment-22968\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22968 size-full\" title=\"Trita la marijuana con un grinder\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-1.jpg\" alt=\"Trita la marijuana con un grinder\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-1.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-1-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22968\" class=\"wp-caption-text\">Trita la marijuana con un grinder<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8211; Prendere una normale tazza da t\u00e8, mettere il colino e aggiungere a quest&#8217;ultimo la marijuana sbriciolata, poi <b>versare sopra l&#8217;acqua con il burro<\/b>. Copri e lascia riposare per <b>3-5 minuti<\/b>. Trascorso questo tempo, hai gi\u00e0 l&#8217;infuso pronto da consumare.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22971\" aria-describedby=\"caption-attachment-22971\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22971 size-full\" title=\"Versare l'acqua con il burro sulla marijuana\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-agua.jpg\" alt=\"Versare l'acqua con il burro sulla marijuana\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-agua.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-agua-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22971\" class=\"wp-caption-text\">Versare l&#8217;acqua con il burro sulla marijuana<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Nella seconda variante di ricetta, prepareremo un <b>infuso di marijuana con il latte<\/b>. Se il primo ti \u00e8 sembrato facile, questo lo \u00e8 ancora di pi\u00f9. Il primo passaggio \u00e8 lo stesso, nel secondo, invece di scaldare l&#8217;acqua, metti il \u200b\u200blatte al fuoco, una volta che inizia a bollire, lo versi sopra la marijuana che avrai nell&#8217;infusore della tazza da t\u00e8. Il tempo di riposo sar\u00e0 lo stesso.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22974\" aria-describedby=\"caption-attachment-22974\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22974 size-full\" title=\"Puoi usare il latte invece dell\u2019acqua\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-leche.jpg\" alt=\"Puoi usare il latte invece dell\u2019acqua\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-leche.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-2-leche-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22974\" class=\"wp-caption-text\">Puoi usare il latte invece dell\u2019acqua<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>In entrambi i casi, se preferisci, puoi prendere un altro colino pulito e <b>filtrare nuovamente l&#8217;infuso<\/b> (l&#8217;acqua o il latte, senza passare la marijuana, solo l&#8217;infuso che \u00e8 rimasto), per assicurarti che non ci siano tracce di erba nella tua bevanda.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22977\" aria-describedby=\"caption-attachment-22977\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22977 size-full\" title=\"Ora \u00e8 il momento di filtrare l'infuso prima di assumerlo\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-agua.jpg\" alt=\"Ora \u00e8 il momento di filtrare l'infuso prima di assumerlo\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-agua.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-agua-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22977\" class=\"wp-caption-text\">Ora \u00e8 il momento di filtrare l&#8217;infuso prima di assumerlo<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p><i>Pi\u00f9 facile di cos\u00ec non si pu\u00f2<\/i>. Ora, se vuoi, come ho detto sopra, puoi aggiungere <b>un dolcificante naturale<\/b>. Se vuoi dargli un altro sapore, dovresti aggiungere una seconda bustina di infusione nello stesso momento in cui versi l&#8217;acqua o il latte nella tazza da t\u00e8, per poi rimuoverla subito dopo.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_22980\" aria-describedby=\"caption-attachment-22980\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-22980 size-full\" title=\"Preparazione identica anche in caso di utilizzo di latte\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-leche.jpg\" alt=\"Preparazione identica anche in caso di utilizzo di latte\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-leche.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/12\/infusion-marihuana-paso-3-leche-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-22980\" class=\"wp-caption-text\">Preparazione identica anche in caso di utilizzo di latte<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>E, a proposito di bustine di infusioni. <i>Sapevi che in Pevgrow hai a disposizione anche <\/i><b><i>bustine di t\u00e8<\/i><\/b><i>?<\/i> Cos\u00ec facendo il tuoo \u00e8 ancora pi\u00f9 semplice e, inoltre, hai ben 3 opzioni a disposizione. E se hai una macchina Nespresso, abbiamo anche <b>capsule compatibili<\/b> con questo tipo di macchina da caff\u00e8 in modo che non ci voglia davvero nulla a preparare un infuso di marijuana quando ne hai voglia.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%F0%9F%9A%80_Proprieta_della_marijuana_in_infusione\"><\/span>\ud83d\ude80 <b>Propriet\u00e0 della marijuana in infusione<\/b><span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Sicuramente se dici a qualcuno che bevi un<a href=\"https:\/\/pevgrow.com\/it\/mix-di-erbe-sessuali.html\"> infuso di marijuana<\/a>, non crederanno che possa davvero trattarsi di una<b> bevanda salutare<\/b>. Pertanto, oltre a prendere in considerazione le precauzioni che ti diremo di seguito per i possibili effetti della marijuana sul tuo corpo, ti interesser\u00e0 scoprire che ha<b> i seguenti benefici<\/b>:<\/p>\n<div class=\"pfgreen\">\n<ul>\n<li>Allevia la nausea<\/li>\n<li>Riduce l&#8217;ansia e la depressione<\/li>\n<li>Migliora la salute cardiovascolare<\/li>\n<li>Previene lo sviluppo dell&#8217;Alzheimer<\/li>\n<li>Riduce il mal di testa<\/li>\n<\/ul>\n<\/div>\n<p>Inoltre, alcuni parlano anche di propriet\u00e0 afrodisiache. <i>Ti aiuta anche in altre occasioni? Forse per dormire meglio?<\/i> \u00c8 vero che tutto <b>dipender\u00e0 dalla variet\u00e0 di marijuana<\/b> che usi. Ma <i>sai per chi questo modo di consumare marijuana \u00e8 davvero pratico e comodo?<\/i> Per chi lo consuma per motivi medici. <b>I suoi effetti sono pi\u00f9 delicati<\/b> e il metodo di assunzione, come ben sai, \u00e8 molto pi\u00f9 semplice, cos\u00ec come il modo in cui si prepara.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E2%9C%85_Quali_effetti_produce\"><\/span>\u2705 <b>Quali effetti produce<\/b>?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Come ben sapete, <b>gli effetti della marijuana fumata non hanno niente a che vedere con quelli dell\u2019erba consumata per via alimentare,<\/b> anche se, in sostanza, sono quasi gli stessi. Ma se, come in questo caso, la bevi, gli effetti impiegano pi\u00f9 tempo a manifestarsi. A seconda della reazione individuale <b>possono passare dai 30 ai 90 minuti<\/b>, per questo \u00e8 sempre meglio aspettare e sorbire l&#8217;infuso poco a poco, fino a vedere l&#8217;effetto che ha su ciascuno.<\/p>\n<p>D&#8217;altra parte, nel caso dell&#8217;infusione di marijuana, <b>gli effetti sono pi\u00f9 lievi<\/b> e, quindi, molto pi\u00f9 piacevoli per chi usa la marijuana per <b>scopi medicinali o salutari.<\/b> Quindi, come abbiamo detto sopra, non sorprende che questo sia uno dei modi preferiti di consumarla.<\/p>\n<p>Molto dipender\u00e0 dal <b>tipo di variet\u00e0 di cannabis<\/b> che abbiamo utilizzato: in base ad essa gli effetti potranno essere pi\u00f9 rilassanti o pi\u00f9 sociali e\/o creativi.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"pfblue w100\">Potresti anche essere interessato a:<br \/>\n&#8211; <a href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-delizioso-cupcake-alla-marijuana\/\">Come preparare un delizioso cupcake alla marijuana<\/a><br \/>\n&#8211; <a href=\"https:\/\/pevgrow.com\/blog\/it\/come-fare-le-caramelle-alla-marijuana\/\">Come fare le caramelle alla marijuana<\/a><br \/>\n&#8211; <a href=\"https:\/\/pevgrow.com\/blog\/it\/come-fare-i-cioccolatini-alla-marijuana\/\">Come preparare i cioccolatini alla marijuana<\/a><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%F0%9F%8E%AF_Conclusioni\"><\/span>\ud83c\udfaf Conclusioni<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Come hai visto, preparare <b>un infuso di marijuana \u00e8 davvero semplice<\/b>. E tu, lo <i>prepari allo stesso modo? Hai qualche aneddoto o trucco al riguardo?<\/i><\/p>\n<p>Ci piacerebbe che ce lo rivelassi e se questo articolo ti \u00e8 piaciuto <b><i>condividilo sui tuoi social network.<\/i><\/b><\/p>\n<p><i>Ci vediamo al prossimo post!<\/i><\/p>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Veramente semplici da preparare, gli t\u00e8 di marijuana hanno il vantaggio che gli effetti sono molto pi\u00f9 miti e che impiegano dai 30 ai 90 minuti per manifestarsi. Oggi vi diciamo come prepararlo, quali sono le sue propriet\u00e0 &#8230; <a title=\"Come preparare un infuso di marijuana\" class=\"read-more\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/\" aria-label=\"Read more about Come preparare un infuso di marijuana\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":10,"featured_media":38944,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_content_score":"30","_yoast_wpseo_meta-robots-noindex":"","_yoast_wpseo_meta-robots-nofollow":"","_yoast_wpseo_bctitle":"","_yoast_wpseo_canonical":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_schema_page_type":"","_yoast_wpseo_schema_article_type":"","yasr_overall_rating":5,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"Recipe","footnotes":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_estimated-reading-time-minutes":"7","_yoast_wpseo_wordproof_timestamp":""},"categories":[525],"tags":[],"class_list":["post-38942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ricette-con-la-marijuana","no-featured-image-padding"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Come fare un infuso di marijuana, [FACILE e VELOCE].<\/title>\n<meta name=\"description\" content=\"Semplice da preparare, l&#039;infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Come fare un infuso di marijuana, [FACILE e VELOCE].\" \/>\n<meta property=\"og:description\" content=\"Semplice da preparare, l&#039;infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/\" \/>\n<meta property=\"og:site_name\" content=\"Pevgrow.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-06T09:30:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-27T14:14:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Jim\u00e9nez\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Jim\u00e9nez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/\"},\"author\":{\"name\":\"Noelia Jim\u00e9nez\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/54b3cfda8a248851448a0e21bdec1d85\"},\"headline\":\"Come preparare un infuso di marijuana\",\"datePublished\":\"2018-02-06T09:30:24+00:00\",\"dateModified\":\"2023-12-27T14:14:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/\"},\"wordCount\":1151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/infusion-marihuana-portada.jpg\",\"articleSection\":[\"Ricette con la marijuana\"],\"inLanguage\":\"it\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/\",\"name\":\"Come fare un infuso di marijuana, [FACILE e VELOCE].\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/infusion-marihuana-portada.jpg\",\"datePublished\":\"2018-02-06T09:30:24+00:00\",\"dateModified\":\"2023-12-27T14:14:09+00:00\",\"description\":\"Semplice da preparare, l'infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#breadcrumb\"},\"inLanguage\":\"it\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/infusion-marihuana-portada.jpg\",\"contentUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/01\\\/infusion-marihuana-portada.jpg\",\"width\":575,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/come-preparare-un-infuso-di-marijuana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ricette con la marijuana\",\"item\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/category\\\/ricette-con-la-marijuana\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/\",\"name\":\"Pevgrow.com\",\"description\":\"Notizie sulla marijuana e consigli per l'autocoltivazione\\r\\n\",\"publisher\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#organization\",\"name\":\"Pevgrow.com\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-logo-pevgrow.png\",\"contentUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-logo-pevgrow.png\",\"width\":342,\"height\":197,\"caption\":\"Pevgrow.com\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/#\\\/schema\\\/person\\\/54b3cfda8a248851448a0e21bdec1d85\",\"name\":\"Noelia Jim\u00e9nez\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g\",\"caption\":\"Noelia Jim\u00e9nez\"},\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/it\\\/author\\\/noelia-jimenez\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Come fare un infuso di marijuana, [FACILE e VELOCE].","description":"Semplice da preparare, l'infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/","og_locale":"it_IT","og_type":"article","og_title":"Come fare un infuso di marijuana, [FACILE e VELOCE].","og_description":"Semplice da preparare, l'infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi","og_url":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/","og_site_name":"Pevgrow.com","article_published_time":"2018-02-06T09:30:24+00:00","article_modified_time":"2023-12-27T14:14:09+00:00","og_image":[{"width":575,"height":400,"url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg","type":"image\/jpeg"}],"author":"Noelia Jim\u00e9nez","twitter_misc":{"Written by":"Noelia Jim\u00e9nez","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#article","isPartOf":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/"},"author":{"name":"Noelia Jim\u00e9nez","@id":"https:\/\/pevgrow.com\/blog\/it\/#\/schema\/person\/54b3cfda8a248851448a0e21bdec1d85"},"headline":"Come preparare un infuso di marijuana","datePublished":"2018-02-06T09:30:24+00:00","dateModified":"2023-12-27T14:14:09+00:00","mainEntityOfPage":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/"},"wordCount":1151,"commentCount":0,"publisher":{"@id":"https:\/\/pevgrow.com\/blog\/it\/#organization"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#primaryimage"},"thumbnailUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg","articleSection":["Ricette con la marijuana"],"inLanguage":"it","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/","url":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/","name":"Come fare un infuso di marijuana, [FACILE e VELOCE].","isPartOf":{"@id":"https:\/\/pevgrow.com\/blog\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#primaryimage"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#primaryimage"},"thumbnailUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg","datePublished":"2018-02-06T09:30:24+00:00","dateModified":"2023-12-27T14:14:09+00:00","description":"Semplice da preparare, l'infuso di marijuana, ha il vantaggio che gli effetti sono molto pi\u00f9 soavi e richiedono tra i 30 e i 90 minuti per manifestarsi","breadcrumb":{"@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#breadcrumb"},"inLanguage":"it","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/"]}]},{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#primaryimage","url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg","contentUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/01\/infusion-marihuana-portada.jpg","width":575,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/pevgrow.com\/blog\/it\/come-preparare-un-infuso-di-marijuana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/pevgrow.com\/blog\/it\/"},{"@type":"ListItem","position":2,"name":"Ricette con la marijuana","item":"https:\/\/pevgrow.com\/blog\/it\/category\/ricette-con-la-marijuana\/"}]},{"@type":"WebSite","@id":"https:\/\/pevgrow.com\/blog\/it\/#website","url":"https:\/\/pevgrow.com\/blog\/it\/","name":"Pevgrow.com","description":"Notizie sulla marijuana e consigli per l'autocoltivazione\r\n","publisher":{"@id":"https:\/\/pevgrow.com\/blog\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pevgrow.com\/blog\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it"},{"@type":"Organization","@id":"https:\/\/pevgrow.com\/blog\/it\/#organization","name":"Pevgrow.com","url":"https:\/\/pevgrow.com\/blog\/it\/","logo":{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/pevgrow.com\/blog\/it\/#\/schema\/logo\/image\/","url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-logo-pevgrow.png","contentUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-logo-pevgrow.png","width":342,"height":197,"caption":"Pevgrow.com"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pevgrow.com\/blog\/it\/#\/schema\/person\/54b3cfda8a248851448a0e21bdec1d85","name":"Noelia Jim\u00e9nez","image":{"@type":"ImageObject","inLanguage":"it","@id":"https:\/\/secure.gravatar.com\/avatar\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34245197299fbfbb02bd98ad521da0c2ec89effbd9fbf832a3792e54467d5fea?s=96&d=mm&r=g","caption":"Noelia Jim\u00e9nez"},"url":"https:\/\/pevgrow.com\/blog\/it\/author\/noelia-jimenez\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":10,"sum_votes":41},"_links":{"self":[{"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/comments?post=38942"}],"version-history":[{"count":0,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/posts\/38942\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/media\/38944"}],"wp:attachment":[{"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/media?parent=38942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/categories?post=38942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/it\/wp-json\/wp\/v2\/tags?post=38942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}