                        {"id":25304,"date":"2018-09-14T10:00:52","date_gmt":"2018-09-14T08:00:52","guid":{"rendered":"https:\/\/pevgrow.com\/blog\/?p=25304"},"modified":"2023-07-14T15:43:12","modified_gmt":"2023-07-14T13:43:12","slug":"como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro","status":"publish","type":"post","link":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/","title":{"rendered":"C\u00f3mo el CBD puede ayudar a tu perro"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_25366\" aria-describedby=\"caption-attachment-25366\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25366 size-full\" title=\"C\u00f3mo el CBD de la marihuana puede ayudar a tu perro\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg\" alt=\"C\u00f3mo el CBD de la marihuana puede ayudar a tu perro\" width=\"575\" height=\"400\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada-300x209.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25366\" class=\"wp-caption-text\">C\u00f3mo el CBD de la marihuana puede ayudar a tu perro<\/figcaption><\/figure>\n        <div class=\"hero-unit-pev\">\n            <div class=\"row-fluid\">\n            <div class=\"span2 text-center\">  \n                <picture>\n                    <source media=\"(max-width: 550px)\" srcset=\"\/blog\/wp-content\/uploads\/2019\/08\/mario-soriano.png\">\n                    <source media=\"(min-width: 770px)\" srcset=\"\/blog\/wp-content\/uploads\/2019\/08\/mario-soriano.png\">\n                    <img decoding=\"async\" loading=\"lazy\" src=\"\/blog\/wp-content\/uploads\/2019\/08\/mario-soriano.png\" width=\"100\" height=\"100\" alt=\"Mario Soriano\" title=\"Mario Soriano\" class=\"firround\">\n                <\/picture>\n            <\/div>\n            <div class=\"span10 firtexto\">\n                <div class=\"firtit\"><a href=\"\/blog\/author\/mario-soriano\/\">Mario Soriano<\/a><\/div>\n                Licenciado en Veterinaria, Ciencia y Tecnolog\u00eda de los Alimentos<br>Apasionado de la marihuana medicinal y firme en el convencimiento de que la marihuana puede ayudar a los animales en diferentes enfermedades.<br>\n                14-09-2018 10:00:52 - Actualizado: 14 September, 2018\n            <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"pev-redes\">\n            <div class=\"pev-rss-top text-center\">\n                <a class=\"pev-wapp\" href=\"https:\/\/api.whatsapp.com\/send?text=https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304\" target=\"_blank\" rel=\"nofollow\" alt=\"Whatsapp\" title=\"Whatsapp\"><\/a>\n                <a class=\"pev-telegram\" href=\"https:\/\/t.me\/share\/url?url=https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304&text=Echa%20un%20vistazo%20a%20esta%20noticia\" target=\"_blank\" rel=\"nofollow\" alt=\"Telegram\" title=\"Telegram\"><\/a>\n                <a class=\"pev-fb\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304\" target=\"_blank\" rel=\"nofollow\" alt=\"Facebook\" title=\"Facebook\"><\/a>\n                <a class=\"pev-tw\" href=\"https:\/\/twitter.com\/intent\/tweet?text=Echa%20un%20vistazo%20a%20esta%20noticia - https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304\" target=\"_blank\" rel=\"nofollow\" alt=\"Twitter\" title=\"Twitter\"><\/a>\n                <a class=\"pev-mail\" href=\"mailto:?subject=\u00a1Mira%20lo%20que%20he%20encontrado%20en%20https:\/\/pevgrow.com!&amp;body=Echa%20un%20vistazo%20a%20esta%20noticia%20https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304.\" target=\"_blank\" rel=\"nofollow\" alt=\"E-mail\" title=\"E-mail\"><\/a>\n            <\/div>\n        <\/div>\n        \n<p>&nbsp;<\/p>\n<p><strong>Los beneficios de los compuestos qu\u00edmicos contenidos en la marihuana,<\/strong> han demostrado en los \u00faltimos a\u00f1os sobrada eficacia en multitud de dolencias en humanos. En la planta de la marihuana quedan contenidos cientos de compuestos qu\u00edmicos de entre los que el denominado <strong>CBD (cannabidiol),<\/strong> se encuentra relacionado con efectos beneficiosos en multitud de enfermedades, que van <strong>desde la epilepsia a la ansiedad<\/strong> pasando por <strong>la artrosis, el c\u00e1ncer o las enfermedades inflamatorias intestinales<\/strong>.<\/p>\n<blockquote><p>En <strong>este enlace<\/strong> puedes ver c\u00f3mo en estos momentos son casi <strong>6000 los estudios cient\u00edficos publicados<\/strong> en revistas de impacto que avalan todo lo que te acabamos de explicar.<\/p><\/blockquote>\n<p>C\u00f3mo no pod\u00eda ser de otra manera, los beneficios de ciertos componentes de la marihuana, como el <strong>CBD<\/strong>, han empezado a probarse <strong>en animales de compa\u00f1\u00eda<\/strong> mostrando resultados tan satisfactorios o m\u00e1s que en humanos. Antes de continuar analizando c\u00f3mo vas a poder ayudar a tu mascota<strong> con el uso de CBD<\/strong> es necesario que entendamos una serie de conceptos clave. Dentro de la planta de la marihuana como hemos dicho hay miles de compuestos qu\u00edmicos, siendo los m\u00e1s conocidos <strong>el THC y el CBD<\/strong>.<\/p>\n<p>Es importante que entiendas que el THC por encima de <strong>ciertas cantidades puede ser t\u00f3xico e incluso mortal para tu mascota<\/strong>. No ocurre lo mismo con el CBD que podemos usar dentro de ciertas dosis en nuestros animales obteniendo efectos beneficiosos en multitud de circunstancias.<\/p>\n<p>Es muy importante esta salvedad porque debemos de utilizar productos <a href=\"https:\/\/pevgrow.com\/4845-cbd-para-mascotas\">CBD <strong>espec\u00edficamente dise\u00f1ados para mascotas<\/strong><\/a> y con formulaci\u00f3n veterinaria; esta es la principal garant\u00eda de cara a que contengan niveles de CBD efectivos, controlados y en la combinaci\u00f3n perfecta. No sirve cualquier presentaci\u00f3n de CBD para los perros y por eso <strong>nuestra formulaci\u00f3n ha sido expresamente dise\u00f1ada para trabajar en los perros<\/strong> de la manera m\u00e1s eficaz.<\/p>\n<p>Para que el CBD sea asimilable por tu perro tenemos que partir de presentaciones <strong>en forma de aceite de uso sublingual<\/strong>; de lo contrario, si simplemente dejamos que lo ingiera su efecto ser\u00e1 mucho menor por el denominado efecto de primer paso. En nuestro <strong><a href=\"https:\/\/pevgrow.com\/\">Grow Shop<\/a><\/strong> encontraras productos tanto para <strong><a href=\"https:\/\/pevgrow.com\/4846-cbd-para-perros\">CBD para perros<\/a><\/strong> y <strong><a href=\"https:\/\/pevgrow.com\/4847-cbd-para-gatos\">CBD para gatos<\/a>.<\/strong> Haz mucho m\u00e1s f\u00e1cil la vida de tu mascota, se lo merece!<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Index<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 eztoc-toggle-hide-by-default' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#%E2%9C%A8_El_CBD_para_perros\" >\u2728 El CBD para perros<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#%C2%BFQue_le_puedo_dar_a_mi_perro_para_el_dolor\" >\u00bfQue le puedo dar a mi perro para el dolor?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#%C2%BFEn_que_enfermedades_de_los_perros_nos_puede_ayudar_el_aceite_de_CBD\" >\u00bfEn qu\u00e9 enfermedades de los perros nos puede ayudar el aceite de CBD?<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Artritis_y_artrosis\" >Artritis y artrosis.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Aceite_de_CBD_para_tratar_el_cancer_de_tu_mascota\" >Aceite de CBD para tratar el c\u00e1ncer de tu mascota<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Ansiedad_y_nerviosismo\" >Ansiedad y nerviosismo.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Convulsiones_y_Epilepsia\" >Convulsiones y Epilepsia.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Control_de_vomitos_y_apetito\" >Control de v\u00f3mitos y apetito.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Dermatitis_y_problemas_de_la_piel\" >Dermatitis y problemas de la piel.<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#Otros_efectos\" >Otros efectos.<\/a><\/li><\/ul><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#%E2%9B%B3_Conclusiones\" >\u26f3 Conclusiones.<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%E2%9C%A8_El_CBD_para_perros\"><\/span>\u2728 El CBD para perros<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>La mol\u00e9cula del <strong>CBD<\/strong> es un <strong>componente NO psicoactivo de la planta Cannabis sativa<\/strong>; es decir, tu perro no experimentar\u00e1 efecto psicoactivo alguno y s\u00ed que se beneficiar\u00e1 de efectos beneficiosos en muchos \u00f3rganos y sistemas lo que nos va a permitir utilizarla en nuestros perros para ayudarles en multitud de circunstancias y dolencias. Afortunadamente, en este momento ya <strong>disponemos de estudios que nos analizan los efectos y el comportamiento del CBD en el organismo canino<\/strong>.<\/p>\n<p>C\u00f3mo seguro que te encontrar\u00e1s en tu entorno a esc\u00e9pticos o quiz\u00e1 tu veterinario no se encuentre plenamente familiarizado con esta mol\u00e9cula, aqu\u00ed debajo te dejamos un nutrido grupo de estudios en torno a la din\u00e1mica de comportamiento del CBD en el organismo canino. Adem\u00e1s, con la compra de nuestro producto dispondr\u00e1s del asesoramiento online de nuestro equipo veterinario. La marihuana para perros gana adeptos cada dia por lo que te animamos a que le apliques CBD a tu perro.<\/p>\n<p>&nbsp;<\/p>\n<div class=\"pfgreen\">Seguidamente te adjunto algunos estudios al respecto:<br \/>\n1- Ensayo de espectrometr\u00eda de masas por cromatograf\u00eda de gases simple y r\u00e1pida para evaluar el Delta 9-Tetrahidrocannabinol y Cannabidiol en perros tratados con Cannabis medicinal para la epilepsia canina.<br \/>\n2- Metabolismo comparativo del cannabidiol en perro, rata y hombre.<br \/>\n3- Metabolitos urinarios del cannabidiol en perros, ratas y hombres y su identificaci\u00f3n por cromatograf\u00eda de gases-espectrometr\u00eda de masas.<br \/>\n4- Farmacocin\u00e9tica de los metabolitos urinarios de cannabidiol en el perro.<br \/>\n5- Identificaci\u00f3n de metabolitos urinarios de cannabidiol en el perro.<br \/>\n6- Identificaci\u00f3n de metabolitos del an\u00e1logo 1&#8243;,1&#8243;-dimetilheptil de cannabidiol en rata y perro in vivo.<br \/>\n7- Identificaci\u00f3n de los conjugados de glucosa como metabolitos urinarios principales del cannabidiol en el perro.<br \/>\n8- Farmacocin\u00e9tica del dimetilheptilo hom\u00f3logo del cannabidiol en perros.<br \/>\n9- Farmacocin\u00e9tica del cannabidiol en perros.<br \/>\n10- Hach\u00eds: s\u00edntesis y actividad del sistema nervioso central de algunos nuevos an\u00e1logos del cannabidiol y derivados oxepin del delta 9-tetrahidrocannabinol.<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFQue_le_puedo_dar_a_mi_perro_para_el_dolor\"><\/span>\u00bfQue le puedo dar a mi perro para el dolor?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p>No son pocas las circunstancias en las que tu perro puede experimentar dolor: desde la m\u00e1s tonta de las acciones cotidianas (resbalones, ca\u00eddas, pisotones involuntarios\u2026.etc) hasta multitud de enfermedades que cursan con dolor como <strong>la artrosis en perros ancianos o las lesiones en perros<\/strong> que hacen deporte asiduamente. En estos casos, es importante que entendamos que <strong>el dolor no es m\u00e1s que una se\u00f1al de aviso<\/strong> del cuerpo de nuestro perro. Hay que interpretarla como una alarma y consultar con nuestro veterinario si la gravedad, alcance, duraci\u00f3n o compromiso de su bienestar es cr\u00edtico. Sin embargo, en este contexto, <strong>el CBD puede ser un aliado poderoso y natural<\/strong> para ayudarnos en el control de dolor de nuestro perro.<\/p>\n<p>El tratamiento del dolor en los perros se suele limitar al uso de <strong>antiinflamatorios y analg\u00e9sicos<\/strong> de diferentes familias qu\u00edmicas. Todos ellos sin excepci\u00f3n, van a tener efectos secundarios que pueden limitar su uso en el tiempo, por lo que disponer de un compuesto a base de CBD espec\u00edficamente formulado para perros es una excelente idea, tanto en nuestro botiqu\u00edn de primeros auxilios como<strong> para ayudar a nuestro perro<\/strong> en enfermedades como la artrosis\/artritis.<\/p>\n<div class=\"pfblue\">Tambi\u00e9n te puede interesar:<br \/>\n&#8211;<a href=\"https:\/\/pevgrow.com\/blog\/que-es-el-cbd\/\">\u00bfQu\u00e9 es el CBD?<\/a><br \/>\n&#8211;<a href=\"https:\/\/pevgrow.com\/blog\/la-guia-definitiva-del-aceite-de-marihuana\/\">La gu\u00eda definitiva del aceite de marihuana<\/a><\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h3><span class=\"ez-toc-section\" id=\"%C2%BFEn_que_enfermedades_de_los_perros_nos_puede_ayudar_el_aceite_de_CBD\"><\/span>\u00bfEn qu\u00e9 enfermedades de los perros nos puede ayudar el aceite de CBD?<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Artritis_y_artrosis\"><\/span>Artritis y artrosis.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Uno de los efectos m\u00e1s potentes y m\u00e1s estudiados del CBD es su <strong>poder antiinflamatorio y analg\u00e9sico (<em>estudio<\/em>)<\/strong>. En los perros suelen aparecer con la edad problemas de movilidad dolorosos ligados a patolog\u00edas como la artritis y al artrosis. Estos diagn\u00f3sticos suponen una p\u00e9rdida de calidad de vida para nuestros perros sin posibilidad de cura o mejora. La utilizaci\u00f3n de antiinflamatorios cl\u00e1sicos, (<strong><a href=\"https:\/\/es.wikipedia.org\/wiki\/Antinflamatorio_no_esteroideo\" target=\"_blank\" rel=\"noopener noreferrer\">AINEs<\/a><\/strong> o corticoides) presenta adem\u00e1s importantes efectos secundarios a medio\/largo plazo, lo que ligado a que hablamos de enfermedades cr\u00f3nicas, hace que <strong>el CBD sea una mol\u00e9cula ideal para ayudar a tu perro<\/strong>. De hecho, en la Universidad de Colorado ya se est\u00e1n concluyendo<strong><em> una investigaci\u00f3n<\/em><\/strong> cuyos resultados son ampliamente prometedores para el manejo del dolor en perros con artrosis.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25369\" aria-describedby=\"caption-attachment-25369\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25369 size-full\" title=\"Artritis y artrosis, un mal que muchos animales sufren.\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/artritis.jpg\" alt=\"Artritis y artrosis, un mal que muchos animales sufren.\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/artritis.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/artritis-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25369\" class=\"wp-caption-text\">Artritis y artrosis, un mal que muchos animales sufren.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><\/h4>\n<h4><span class=\"ez-toc-section\" id=\"Aceite_de_CBD_para_tratar_el_cancer_de_tu_mascota\"><\/span>Aceite de CBD para tratar el c\u00e1ncer de tu mascota<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Uno de los campos de utilizaci\u00f3n del CBD en humanos es por sus <strong>propiedades anticancer\u00edgenas<\/strong>. De hecho, en <strong><em>este enlace<\/em><\/strong> puedes ver 104 art\u00edculos cient\u00edficos de revistas de impacto en los que se vincula el CBD con propiedades anticancer\u00edgenas. Hasta la fecha, hemos considerado al CBD como una sustancia paliativa debido a sus efectos analg\u00e9sicos y antiem\u00e9ticos (<strong>control del v\u00f3mito<\/strong>), sin embargo, un n\u00famero creciente de estudios precl\u00ednicos indica sus propiedades contra el c\u00e1ncer.<\/p>\n<p>Los cannabinoides CBD act\u00faan mediante la modulaci\u00f3n de las v\u00edas de comunicaci\u00f3n de las c\u00e9lulas cancerosas, el control de la proliferaci\u00f3n celular y la supervivencia de las c\u00e9lulas cancerosas. Muchos experimentos in vitro e in vivo han demostrado que <strong>el CBD inhibe la proliferaci\u00f3n de las c\u00e9lulas cancerosas<\/strong>, estimulan la autofagia (destrucci\u00f3n del tumor) y la apoptosis (muerte programada de las c\u00e9lulas cancerosas) y tambi\u00e9n <strong>tienen el potencial de inhibir la angiog\u00e9nesis<\/strong> (desarrollo de vasos sangu\u00edneos del tumor) y la met\u00e1stasis.<\/p>\n<p>Por todo ello, si tu perro tiene c\u00e1ncer, el CBD puede ser un mol\u00e9cula aliada en su proceso tal y como nos muestra alguna fuente de referencia como Veterinary Practice News. CBD para perros puede ser tu mejor remedio. <strong><em>en este art\u00edculo<\/em><\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25372\" aria-describedby=\"caption-attachment-25372\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25372 size-full\" title=\"Aceite de CBD para tratar el c\u00e1ncer de tu mascota\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/cancer.jpg\" alt=\"Aceite de CBD para tratar el c\u00e1ncer de tu mascota\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/cancer.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/cancer-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25372\" class=\"wp-caption-text\">Aceite de CBD para tratar el c\u00e1ncer de tu mascota<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Ansiedad_y_nerviosismo\"><\/span>Ansiedad y nerviosismo.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>El CBD interacciona con una serie de receptores que se encuentran el sistema nervioso central, es decir, el cerebro y la m\u00e9dula espinal. La actuaci\u00f3n del CBD a este nivel se ha relacionado en multitud de estudios con efectos beneficiosos en el <strong>control del estr\u00e9s y la ansiedad<\/strong>. En <strong><em>este enlace<\/em><\/strong> puedes ver un total de <strong>145 art\u00edculos cient\u00edficos relacionados con este hecho<\/strong> y an\u00e1logamente a como sucede en humanos, el CBD utilizado en perros puede ayudar en el manejo de ansiedad, estr\u00e9s y nerviosismo tal y como se ha experimentado en varias pruebas preliminares.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25387\" aria-describedby=\"caption-attachment-25387\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25387 size-full\" title=\"Muchas razas, sobre todo perros son particularmente nerviosos y sufren ansiedad.\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/ansiedad.jpg\" alt=\"Muchas razas, sobre todo perros son particularmente nerviosos y sufren ansiedad.\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/ansiedad.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/ansiedad-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25387\" class=\"wp-caption-text\">Muchas razas, sobre todo perros son particularmente nerviosos y sufren ansiedad.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Convulsiones_y_Epilepsia\"><\/span>Convulsiones y Epilepsia.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Uno de los primeros focos de atenci\u00f3n del CBD fue el manejo de <strong>las convulsiones en general y de la epilepsia en particular<\/strong>. A este respecto, son innumerables las evidencias cient\u00edficas como puedes ver en <strong><em>este enlace<\/em><\/strong> donde se listan <strong>177 art\u00edculos<\/strong> al respecto. Son muchos los casos de epilepsias caninas que no responden a f\u00e1rmacos convencionales o en las que estos se vuelven excesivamente t\u00f3xicos al mantenerlos en el tiempo. Y es precisamente en estos casos donde el uso de CBD en tu perro puede marcar la diferencia en el control de sus convulsiones.<\/p>\n<p>Tal es el \u00e9xito que han empezado a obtener muchos veterinarios en USA que la propia Universidad de Colorado se ha interesado al respecto y la<em><strong> Dra. Stephanie McGrath<\/strong><\/em> conduce en la actualidad <strong><em>un estudio pionero<\/em><\/strong> para concretar <strong>c\u00f3mo y cu\u00e1ndo utilizar el CBD en epilepsia<\/strong> de la manera m\u00e1s \u00f3ptima posible.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25375\" aria-describedby=\"caption-attachment-25375\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25375 size-full\" title=\"Ayudemos a nuestras mascotas con las Convulsiones y la Epilepsia\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/epilepsia.jpg\" alt=\"Ayudemos a nuestras mascotas con las Convulsiones y la Epilepsia\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/epilepsia.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/epilepsia-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25375\" class=\"wp-caption-text\">Ayudemos a nuestras mascotas con las Convulsiones y la Epilepsia<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Control_de_vomitos_y_apetito\"><\/span>Control de v\u00f3mitos y apetito.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Todos hemos tenido en alguna ocasi\u00f3n un cuadro de v\u00f3mito de nuestras mascotas. Normalmente suelen resolverse con una dieta adecuada, reposo y la utilizaci\u00f3n de alg\u00fan f\u00e1rmaco que bloquee el v\u00f3mito: los conocidos como antiem\u00e9ticos. En ocasiones hay otras patolog\u00edas como el c\u00e1ncer que requieren el uso de f\u00e1rmacos que acaban por producir v\u00f3mitos como efecto secundario no pudiendo prescindir de ellos. En todos estos aspectos, el uso de CBD act\u00faa<strong> a nivel del sistema nervioso evitando los v\u00f3mitos e induciendo apetito<\/strong>, lo que es un factor muy positivo para mejorar la recuperaci\u00f3n de muchas enfermedades que dejan inapetentes a nuestras mascotas.<\/p>\n<p>Casi <strong>50 <em>estudios<\/em> avalan este hecho<\/strong>, muchos de ellos ya hechos en animales y podemos beneficiarnos de ello en nuestros perros.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25390\" aria-describedby=\"caption-attachment-25390\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25390 size-full\" title=\"Los animales de compania tambien necesitar ayuda en caso v\u00f3mitos y falta de apetito\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/apetito.jpg\" alt=\"Los animales de compania tambien necesitar ayuda en caso v\u00f3mitos y falta de apetito\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/apetito.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/apetito-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25390\" class=\"wp-caption-text\">Los animales de compania tambien necesitar ayuda en caso v\u00f3mitos y falta de apetito<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Dermatitis_y_problemas_de_la_piel\"><\/span>Dermatitis y problemas de la piel.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Durante los \u00faltimos a\u00f1os se han desarrollado muchos <a href=\"https:\/\/www.ncbi.nlm.nih.gov\/pmc\/?term=cannabidiol+dermatitis\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><em>estudios<\/em><\/strong><\/a> (m\u00e1s de 100 en estos momentos) que relacionan el uso del CBD con el <strong>control de varios mecanismos inflamatorios e inmunol\u00f3gicos de las enfermedades dermatol\u00f3gicas<\/strong>.<\/p>\n<p>En la actualidad, los cambios en los contaminantes atmosf\u00e9ricos, efectos diet\u00e9ticos y toda una serie de factores desconocidos han hecho que se hayan incrementado exponencialmente las enfermedades dermatol\u00f3gicas en perros. Quien tiene un perro con alguna de ellas sabe lo insidioso y de dif\u00edcil de manejo que pueden llegar a ser, sin contar con la merma del bienestar de nuestro perro con los picores constantes, alopecias, heridas, etc.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25384\" aria-describedby=\"caption-attachment-25384\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25384 size-full\" title=\"Algunos animales presentan Dermatitis y problemas en la piel muy molestos.\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/piel.jpg\" alt=\"Algunos animales presentan Dermatitis y problemas en la piel muy molestos.\" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/piel.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/piel-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25384\" class=\"wp-caption-text\">Algunos animales presentan Dermatitis y problemas en la piel muy molestos.<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Otros_efectos\"><\/span>Otros efectos.<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>El CBD act\u00faa <strong>a nivel del sistema endocannabinoide (SE)<\/strong> que tienen todos los mam\u00edferos en general y por tanto tu perro. El SE se encuentra relacionado con centros reguladores de conducta, relajaci\u00f3n, apetito as\u00ed como con<strong> funciones gastrointestinales y antiinflamatorias.<\/strong> Se localiza a lo largo de todo el organismo de tu perro por lo que, dado que hasta la fecha<strong> no se han encontrado efectos nocivos ni l\u00edmites de toxicidad<\/strong> podemos usarlo para mejorar su salud en general y su recuperaci\u00f3n y convalecencia de multitud de enfermedades. La marihuana para perros abre un abanico de posibilidades.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25381\" aria-describedby=\"caption-attachment-25381\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25381 size-full\" title=\"El CBD ayuda a mejorar su salud en general \" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/otros-efectos.jpg\" alt=\"El CBD ayuda a mejorar su salud en general \" width=\"575\" height=\"200\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/otros-efectos.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/otros-efectos-300x104.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25381\" class=\"wp-caption-text\">El CBD ayuda a mejorar su salud en general<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%E2%9B%B3_Conclusiones\"><\/span>\u26f3 Conclusiones.<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>El CBD es un grupo de sustancias naturalmente presentes en la planta de la marihuana pero <strong>carentes de efecto psicoactivo<\/strong> alguno y, por tanto, correctamente utilizadas son una mol\u00e9cula segura y de gran efectividad para varias patolog\u00edas de tu perro. Es tal y como lo lees, marihuana para perros.<\/p>\n<p>El uso de CBD en perros va a permitir<strong> mejorar muchas dolencias<\/strong> pudiendo llegar a ser la clave en el manejo de algunas enfermedades como la artrosis o las convulsiones.<\/p>\n<p>La efectividad del CBD va a estar relacionada con<strong> la combinaci\u00f3n exacta de CBDs<\/strong> que usemos, su presentaci\u00f3n <strong>y modo de administraci\u00f3n y la dosis<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_25360\" aria-describedby=\"caption-attachment-25360\" style=\"width: 565px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-25360 size-full\" title=\"Haz mucho m\u00e1s f\u00e1cil la vida de tu mascota, se lo merece!\" src=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/conclusiones.jpg\" alt=\"Haz mucho m\u00e1s f\u00e1cil la vida de tu mascota, se lo merece!\" width=\"575\" height=\"400\" srcset=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/conclusiones.jpg 575w, https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/conclusiones-300x209.jpg 300w\" sizes=\"(max-width: 575px) 100vw, 575px\" \/><figcaption id=\"caption-attachment-25360\" class=\"wp-caption-text\">Haz mucho m\u00e1s f\u00e1cil la vida de tu mascota, se lo merece!<\/figcaption><\/figure>\n<div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; &nbsp; Los beneficios de los compuestos qu\u00edmicos contenidos en la marihuana, han demostrado en los \u00faltimos a\u00f1os sobrada eficacia en multitud de dolencias en humanos. En la planta de la marihuana quedan contenidos cientos de compuestos qu\u00edmicos de entre &#8230; <a title=\"C\u00f3mo el CBD puede ayudar a tu perro\" class=\"read-more\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/\" aria-label=\"Read more about C\u00f3mo el CBD puede ayudar a tu perro\">Leer m\u00e1s<\/a><\/p>\n","protected":false},"author":9,"featured_media":25366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_wpseo_content_score":"90","_yoast_wpseo_meta-robots-noindex":"","_yoast_wpseo_meta-robots-nofollow":"","_yoast_wpseo_bctitle":"","_yoast_wpseo_canonical":"","_yoast_wpseo_opengraph-title":"","_yoast_wpseo_opengraph-description":"","_yoast_wpseo_schema_page_type":"","_yoast_wpseo_schema_article_type":"","yasr_overall_rating":4.9,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"BlogPosting","footnotes":"","_yoast_wpseo_twitter-title":"","_yoast_wpseo_twitter-description":"","_yoast_wpseo_estimated-reading-time-minutes":"12","_yoast_wpseo_wordproof_timestamp":""},"categories":[619],"tags":[],"class_list":["post-25304","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cbd","no-featured-image-padding"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores<\/title>\n<meta name=\"description\" content=\"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores\" \/>\n<meta property=\"og:description\" content=\"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/\" \/>\n<meta property=\"og:site_name\" content=\"Pevgrow.com\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-14T08:00:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-14T13:43:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario Soriano\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Soriano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/\"},\"author\":{\"name\":\"Mario Soriano\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#\\\/schema\\\/person\\\/445380b01c9dfa82729520b0ed3ee2ea\"},\"headline\":\"C\u00f3mo el CBD puede ayudar a tu perro\",\"datePublished\":\"2018-09-14T08:00:52+00:00\",\"dateModified\":\"2023-07-14T13:43:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/\"},\"wordCount\":2285,\"commentCount\":42,\"publisher\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/portada.jpg\",\"articleSection\":[\"CBD\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/\",\"name\":\"\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/portada.jpg\",\"datePublished\":\"2018-09-14T08:00:52+00:00\",\"dateModified\":\"2023-07-14T13:43:12+00:00\",\"description\":\"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/portada.jpg\",\"contentUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/portada.jpg\",\"width\":575,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Marihuana medicinal\",\"item\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/category\\\/articulos-marihuana-medicinal\\\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/\",\"name\":\"Pevgrow.com\",\"description\":\"Noticias sobre la marihuana y consejos para su autocultivo\",\"publisher\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#organization\",\"name\":\"Pevgrow.com\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-logo-pevgrow.png\",\"contentUrl\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/05\\\/cropped-logo-pevgrow.png\",\"width\":342,\"height\":197,\"caption\":\"Pevgrow.com\"},\"image\":{\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/#\\\/schema\\\/person\\\/445380b01c9dfa82729520b0ed3ee2ea\",\"name\":\"Mario Soriano\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g\",\"caption\":\"Mario Soriano\"},\"url\":\"https:\\\/\\\/pevgrow.com\\\/blog\\\/author\\\/mario-soriano\\\/\"},false]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores","description":"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/","og_locale":"es_ES","og_type":"article","og_title":"\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores","og_description":"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre","og_url":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/","og_site_name":"Pevgrow.com","article_published_time":"2018-09-14T08:00:52+00:00","article_modified_time":"2023-07-14T13:43:12+00:00","og_image":[{"width":575,"height":400,"url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg","type":"image\/jpeg"}],"author":"Mario Soriano","twitter_misc":{"Written by":"Mario Soriano","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#article","isPartOf":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/"},"author":{"name":"Mario Soriano","@id":"https:\/\/pevgrow.com\/blog\/#\/schema\/person\/445380b01c9dfa82729520b0ed3ee2ea"},"headline":"C\u00f3mo el CBD puede ayudar a tu perro","datePublished":"2018-09-14T08:00:52+00:00","dateModified":"2023-07-14T13:43:12+00:00","mainEntityOfPage":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/"},"wordCount":2285,"commentCount":42,"publisher":{"@id":"https:\/\/pevgrow.com\/blog\/#organization"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#primaryimage"},"thumbnailUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg","articleSection":["CBD"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/","url":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/","name":"\ud83e\udd47 \u25b7 El CBD para Perros \ud83e\udd47 Calma sus dolores","isPartOf":{"@id":"https:\/\/pevgrow.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#primaryimage"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#primaryimage"},"thumbnailUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg","datePublished":"2018-09-14T08:00:52+00:00","dateModified":"2023-07-14T13:43:12+00:00","description":"Las propiedades medicinales de la marihuana pueden ayudar a tu perro con sus enfermedades y molestias \u2705 Tratamiento natural para el mejor amigo del hombre","breadcrumb":{"@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#primaryimage","url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg","contentUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2018\/09\/portada.jpg","width":575,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/pevgrow.com\/blog\/como-el-cbd-de-la-marihuana-puede-ayudar-a-tu-perro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/pevgrow.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Marihuana medicinal","item":"https:\/\/pevgrow.com\/blog\/category\/articulos-marihuana-medicinal\/"}]},{"@type":"WebSite","@id":"https:\/\/pevgrow.com\/blog\/#website","url":"https:\/\/pevgrow.com\/blog\/","name":"Pevgrow.com","description":"Noticias sobre la marihuana y consejos para su autocultivo","publisher":{"@id":"https:\/\/pevgrow.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pevgrow.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/pevgrow.com\/blog\/#organization","name":"Pevgrow.com","url":"https:\/\/pevgrow.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/pevgrow.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-logo-pevgrow.png","contentUrl":"https:\/\/pevgrow.com\/blog\/wp-content\/uploads\/2023\/05\/cropped-logo-pevgrow.png","width":342,"height":197,"caption":"Pevgrow.com"},"image":{"@id":"https:\/\/pevgrow.com\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pevgrow.com\/blog\/#\/schema\/person\/445380b01c9dfa82729520b0ed3ee2ea","name":"Mario Soriano","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4795fff59de96720b686554c3c3b0b2a7cca2eaabe3f440de2ad36a9f85fe7e6?s=96&d=mm&r=g","caption":"Mario Soriano"},"url":"https:\/\/pevgrow.com\/blog\/author\/mario-soriano\/"},false]}},"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":24,"sum_votes":102},"_links":{"self":[{"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/comments?post=25304"}],"version-history":[{"count":0,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/posts\/25304\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/media\/25366"}],"wp:attachment":[{"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/media?parent=25304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/categories?post=25304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pevgrow.com\/blog\/wp-json\/wp\/v2\/tags?post=25304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}